{"id":110880,"date":"2025-03-31T09:05:35","date_gmt":"2025-03-31T07:05:35","guid":{"rendered":"https:\/\/www.eurofirms.com\/es\/testimoniales\/jose-juan-mendez\/"},"modified":"2025-03-31T09:05:35","modified_gmt":"2025-03-31T07:05:35","slug":"jose-juan-mendez","status":"publish","type":"clientes-opinan","link":"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/","title":{"rendered":"Jos\u00e9 Juan M\u00e9ndez"},"content":{"rendered":"","protected":false},"template":"","categoria-testimoniales":[],"class_list":["post-110880","clientes-opinan","type-clientes-opinan","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jos\u00e9 Juan M\u00e9ndez - Eurofirms<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Juan M\u00e9ndez - Eurofirms\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurofirms\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/testimoniales\\\/jose-juan-mendez\\\/\",\"url\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/testimoniales\\\/jose-juan-mendez\\\/\",\"name\":\"Jos\u00e9 Juan M\u00e9ndez - Eurofirms\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/#website\"},\"datePublished\":\"2025-03-31T07:05:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/testimoniales\\\/jose-juan-mendez\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/testimoniales\\\/jose-juan-mendez\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/testimoniales\\\/jose-juan-mendez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimoniales\",\"item\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/testimoniales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jos\u00e9 Juan M\u00e9ndez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/\",\"name\":\"Eurofirms\",\"description\":\"Eurofirms\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/#organization\",\"name\":\"Eurofirms\",\"url\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/logo-eurofirms-people-first.webp\",\"contentUrl\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/logo-eurofirms-people-first.webp\",\"width\":130,\"height\":38,\"caption\":\"Eurofirms\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eurofirms.com\\\/es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Juan M\u00e9ndez - Eurofirms","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Jos\u00e9 Juan M\u00e9ndez - Eurofirms","og_url":"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/","og_site_name":"Eurofirms","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/","url":"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/","name":"Jos\u00e9 Juan M\u00e9ndez - Eurofirms","isPartOf":{"@id":"https:\/\/www.eurofirms.com\/es\/en\/#website"},"datePublished":"2025-03-31T07:05:35+00:00","breadcrumb":{"@id":"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/jose-juan-mendez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eurofirms.com\/es\/en\/"},{"@type":"ListItem","position":2,"name":"Testimoniales","item":"https:\/\/www.eurofirms.com\/es\/en\/testimoniales\/"},{"@type":"ListItem","position":3,"name":"Jos\u00e9 Juan M\u00e9ndez"}]},{"@type":"WebSite","@id":"https:\/\/www.eurofirms.com\/es\/en\/#website","url":"https:\/\/www.eurofirms.com\/es\/en\/","name":"Eurofirms","description":"Eurofirms","publisher":{"@id":"https:\/\/www.eurofirms.com\/es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eurofirms.com\/es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eurofirms.com\/es\/en\/#organization","name":"Eurofirms","url":"https:\/\/www.eurofirms.com\/es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eurofirms.com\/es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.eurofirms.com\/es\/wp-content\/uploads\/sites\/2\/2025\/02\/logo-eurofirms-people-first.webp","contentUrl":"https:\/\/www.eurofirms.com\/es\/wp-content\/uploads\/sites\/2\/2025\/02\/logo-eurofirms-people-first.webp","width":130,"height":38,"caption":"Eurofirms"},"image":{"@id":"https:\/\/www.eurofirms.com\/es\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.eurofirms.com\/es\/en\/wp-json\/wp\/v2\/clientes-opinan\/110880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eurofirms.com\/es\/en\/wp-json\/wp\/v2\/clientes-opinan"}],"about":[{"href":"https:\/\/www.eurofirms.com\/es\/en\/wp-json\/wp\/v2\/types\/clientes-opinan"}],"wp:attachment":[{"href":"https:\/\/www.eurofirms.com\/es\/en\/wp-json\/wp\/v2\/media?parent=110880"}],"wp:term":[{"taxonomy":"categoria-testimoniales","embeddable":true,"href":"https:\/\/www.eurofirms.com\/es\/en\/wp-json\/wp\/v2\/categoria-testimoniales?post=110880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}